{"id":29045,"date":"2026-05-04T19:01:27","date_gmt":"2026-05-04T17:01:27","guid":{"rendered":"https:\/\/timeforchopin.eu\/events\/koncert-chopinowski-06-07-1800\/"},"modified":"2026-05-04T19:04:35","modified_gmt":"2026-05-04T17:04:35","slug":"koncert-chopinowski-06-07-1800","status":"publish","type":"ajde_events","link":"https:\/\/timeforchopin.eu\/en\/events\/koncert-chopinowski-06-07-1800\/","title":{"rendered":"Chopin Concert 06.07 -18:00"},"content":{"rendered":"<p>tba<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"tags":[],"event_type":[],"event_type_2":[],"class_list":["post-29045","ajde_events","type-ajde_events","status-publish","hentry","event_location-pleyel-salon-kanonia-20-22","event_organizer-time-for-chopin-en"],"_links":{"self":[{"href":"https:\/\/timeforchopin.eu\/en\/wp-json\/wp\/v2\/ajde_events\/29045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timeforchopin.eu\/en\/wp-json\/wp\/v2\/ajde_events"}],"about":[{"href":"https:\/\/timeforchopin.eu\/en\/wp-json\/wp\/v2\/types\/ajde_events"}],"author":[{"embeddable":true,"href":"https:\/\/timeforchopin.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timeforchopin.eu\/en\/wp-json\/wp\/v2\/comments?post=29045"}],"wp:attachment":[{"href":"https:\/\/timeforchopin.eu\/en\/wp-json\/wp\/v2\/media?parent=29045"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timeforchopin.eu\/en\/wp-json\/wp\/v2\/tags?post=29045"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/timeforchopin.eu\/en\/wp-json\/wp\/v2\/event_type?post=29045"},{"taxonomy":"event_type_2","embeddable":true,"href":"https:\/\/timeforchopin.eu\/en\/wp-json\/wp\/v2\/event_type_2?post=29045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}